{"id":1010,"date":"2024-08-10T14:26:41","date_gmt":"2024-08-10T19:26:41","guid":{"rendered":"https:\/\/boutiquefloralec.com\/?post_type=product&#038;p=1010"},"modified":"2025-09-13T18:24:48","modified_gmt":"2025-09-13T23:24:48","slug":"anillo-doble-corazon-brillante","status":"publish","type":"product","link":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/","title":{"rendered":"Anillo Doble Coraz\u00f3n Brillante"},"content":{"rendered":"<p><strong>Talla: <\/strong>( USA)<strong> 6 &#8211; <\/strong>(ES)<strong> 52<\/strong><\/p>\n<p><strong>Talla: <\/strong>( USA)<strong> 7 &#8211; <\/strong>(ES)<strong> 54<\/strong><\/p>\n<p><strong>Talla: <\/strong>( USA)<strong> 8 &#8211; <\/strong>(ES)<strong> 56<\/strong><\/p>\n<p>En caso de requerir una talla diferente a las disponibles, su compra se realizar\u00e1 bajo pedido. El tiempo de entrega estar\u00e1 sujeto a un m\u00e1ximo de 25 d\u00edas a partir de la fecha de compra. Si necesita ayuda, no dude en contactarnos\u00a0 por medio de nuestro WhatsApp al 0980924052.<\/p>\n<p class=\"\"><strong>Tiempo de Entrega :<\/strong> 24 H00 -48 H00 varia seg\u00fan Ciudades .<\/p>\n<p class=\"\"><strong>Env\u00edos a Domicilio<\/strong>\u00a0<strong>:\u00a0<\/strong>Los costos por env\u00edos a Domicilio ya se incluyen si realizas el pago con tarjeta de cr\u00e9dito.<\/p>\n<p class=\"\">En el caso de pagos con transferencia bancaria , se adiciona al precio el costo de envi\u00f3.<\/p>\n<p class=\"\">Dentro de la ciudad $1,50-$ 2,00 y en env\u00edos Nacionales $6,00 por paquete.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<p>El Anillo Doble Coraz\u00f3n Brillante presenta dos circonitas c\u00fabicas en forma de coraz\u00f3n, colocadas en \u00e1ngulos distintos para simbolizar el amor entre madre e hijo. La banda del anillo est\u00e1 acentuada con una media fila de pav\u00e9 y se une de manera asim\u00e9trica a los dos corazones, ofreciendo un toque moderno. Un regalo que celebra todo lo que mam\u00e1 ha hecho por ti.<\/p>\n<p><strong>Si solicita otra talla especificar en detalles del envi\u00f3 y contactarse de nosotros para un proceso mas r\u00e1pido de tu compra<\/strong><\/p>\n","protected":false},"featured_media":1013,"template":"","meta":[],"product_brand":[],"product_cat":[36],"product_tag":[],"class_list":["post-1010","product","type-product","status-publish","has-post-thumbnail","product_cat-anillos","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anillo Doble Coraz\u00f3n Brillante - Boutique Floral<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anillo Doble Coraz\u00f3n Brillante - Boutique Floral\" \/>\n<meta property=\"og:description\" content=\"&nbsp;  El Anillo Doble Coraz\u00f3n Brillante presenta dos circonitas c\u00fabicas en forma de coraz\u00f3n, colocadas en \u00e1ngulos distintos para simbolizar el amor entre madre e hijo. La banda del anillo est\u00e1 acentuada con una media fila de pav\u00e9 y se une de manera asim\u00e9trica a los dos corazones, ofreciendo un toque moderno. Un regalo que celebra todo lo que mam\u00e1 ha hecho por ti.  Si solicita otra talla especificar en detalles del envi\u00f3 y contactarse de nosotros para un proceso mas r\u00e1pido de tu compra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/\" \/>\n<meta property=\"og:site_name\" content=\"Boutique Floral\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/boutiquefloralec\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T23:24:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/08\/191198C01_RGB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/\",\"url\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/\",\"name\":\"Anillo Doble Coraz\u00f3n Brillante - Boutique Floral\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boutiquefloralec.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/191198C01_RGB.jpg\",\"datePublished\":\"2024-08-10T19:26:41+00:00\",\"dateModified\":\"2025-09-13T23:24:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boutiquefloralec.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/191198C01_RGB.jpg\",\"contentUrl\":\"https:\\\/\\\/boutiquefloralec.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/191198C01_RGB.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/producto\\\/anillo-doble-corazon-brillante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/boutiquefloralec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/boutiquefloralec.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anillo Doble Coraz\u00f3n Brillante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/#website\",\"url\":\"https:\\\/\\\/boutiquefloralec.com\\\/\",\"name\":\"Boutique Floral\",\"description\":\"Descubre Boutique Floral, la tienda online de regalos premium en Ecuador. Rosas preservadas, bons\u00e1is, joyer\u00eda fina, carteras y accesorios env\u00edos nacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boutiquefloralec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/#organization\",\"name\":\"Boutique Floral\",\"alternateName\":\"Boutiquefloral.ecu\",\"url\":\"https:\\\/\\\/boutiquefloralec.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/boutiquefloralec.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1.png\",\"contentUrl\":\"http:\\\/\\\/boutiquefloralec.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1.png\",\"width\":2500,\"height\":1800,\"caption\":\"Boutique Floral\"},\"image\":{\"@id\":\"https:\\\/\\\/boutiquefloralec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/boutiquefloralec\\\/\",\"https:\\\/\\\/www.instagram.com\\\/boutiquefloral.ecu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anillo Doble Coraz\u00f3n Brillante - Boutique Floral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/","og_locale":"es_ES","og_type":"article","og_title":"Anillo Doble Coraz\u00f3n Brillante - Boutique Floral","og_description":"&nbsp;  El Anillo Doble Coraz\u00f3n Brillante presenta dos circonitas c\u00fabicas en forma de coraz\u00f3n, colocadas en \u00e1ngulos distintos para simbolizar el amor entre madre e hijo. La banda del anillo est\u00e1 acentuada con una media fila de pav\u00e9 y se une de manera asim\u00e9trica a los dos corazones, ofreciendo un toque moderno. Un regalo que celebra todo lo que mam\u00e1 ha hecho por ti.  Si solicita otra talla especificar en detalles del envi\u00f3 y contactarse de nosotros para un proceso mas r\u00e1pido de tu compra","og_url":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/","og_site_name":"Boutique Floral","article_publisher":"https:\/\/www.facebook.com\/boutiquefloralec\/","article_modified_time":"2025-09-13T23:24:48+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/08\/191198C01_RGB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/","url":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/","name":"Anillo Doble Coraz\u00f3n Brillante - Boutique Floral","isPartOf":{"@id":"https:\/\/boutiquefloralec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/#primaryimage"},"image":{"@id":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/#primaryimage"},"thumbnailUrl":"https:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/08\/191198C01_RGB.jpg","datePublished":"2024-08-10T19:26:41+00:00","dateModified":"2025-09-13T23:24:48+00:00","breadcrumb":{"@id":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/#primaryimage","url":"https:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/08\/191198C01_RGB.jpg","contentUrl":"https:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/08\/191198C01_RGB.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/boutiquefloralec.com\/index.php\/producto\/anillo-doble-corazon-brillante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/boutiquefloralec.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/boutiquefloralec.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Anillo Doble Coraz\u00f3n Brillante"}]},{"@type":"WebSite","@id":"https:\/\/boutiquefloralec.com\/#website","url":"https:\/\/boutiquefloralec.com\/","name":"Boutique Floral","description":"Descubre Boutique Floral, la tienda online de regalos premium en Ecuador. Rosas preservadas, bons\u00e1is, joyer\u00eda fina, carteras y accesorios env\u00edos nacionales","publisher":{"@id":"https:\/\/boutiquefloralec.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boutiquefloralec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/boutiquefloralec.com\/#organization","name":"Boutique Floral","alternateName":"Boutiquefloral.ecu","url":"https:\/\/boutiquefloralec.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/boutiquefloralec.com\/#\/schema\/logo\/image\/","url":"http:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/10\/1.png","contentUrl":"http:\/\/boutiquefloralec.com\/wp-content\/uploads\/2024\/10\/1.png","width":2500,"height":1800,"caption":"Boutique Floral"},"image":{"@id":"https:\/\/boutiquefloralec.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/boutiquefloralec\/","https:\/\/www.instagram.com\/boutiquefloral.ecu"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/product\/1010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/media\/1013"}],"wp:attachment":[{"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/media?parent=1010"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=1010"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1010"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/boutiquefloralec.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}